{"id":2520,"date":"2020-01-17T19:40:48","date_gmt":"2020-01-17T18:40:48","guid":{"rendered":"https:\/\/www.rossocorsa.es\/?post_type=wpb_portfolio&#038;p=2520"},"modified":"2023-10-10T10:52:11","modified_gmt":"2023-10-10T08:52:11","slug":"ferrari-360-f-spider-f1-3","status":"publish","type":"portfolio","link":"https:\/\/www.rossocorsa.gi\/es\/portfolio\/ferrari-360-f-spider-f1-3\/","title":{"rendered":"Ferrari 360 Spider F1"},"content":{"rendered":"<p>Exclusividad y elegancia Italiana. El dise\u00f1o de este Ferrari 360 Spider destaca por la transparencia de la tapa de su motor, que permite al conductor observarlo desde fuera, sus din\u00e1micas l\u00edneas en los laterales y su combinaci\u00f3n de colores.<\/p>\n<p>El interior en cuero beige y su precioso volante Rojo le da un aspecto a\u00fan m\u00e1s deportivo.<\/p>\n<p>Esta joya italiana sobrepasa los 290 Km\/h, gracias en parte a su ligero peso y su motor V8 empujado por 400CV. Es capaz de alcanzar los 0 a 100 Km\/h en solo 4,6 segundos.<\/p>\n<p>Incluye faros de xen\u00f3n, control de tracci\u00f3n ASR (importante para derrapes de alta velocidad), y direcci\u00f3n asistida de endurecimiento progresivo. \u00a1Conducirlo es un placer! \u00a1Seguro que te conquista!<\/p>\n<p>Est\u00e1 en perfectas condiciones, nunca ha tenido accidentes. Disponemos de toda la documentaci\u00f3n y libro de revisiones actualizados.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Interior en cuero rojo con costuras rojas<\/li>\n<li>Aros antivuelco<\/li>\n<li>Pinzas de freno rojas<\/li>\n<li>Asientos Daytona con Cavallino cosido en los reposacabezas<\/li>\n<li>Parilla trasera en fibra de carbono<\/li>\n<li>Logotipo de Ferrari<\/li>\n<li>Escudos de la Scuderia Ferrari en ambos lados<\/li>\n<li>Volante en fibra de carbono<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>My name is Vera<\/p>","protected":false},"featured_media":6570,"template":"","meta":[],"automobile":[30],"features":[],"class_list":["post-2520","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","automobile-30"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/portfolio\/2520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/media\/6570"}],"wp:attachment":[{"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/media?parent=2520"}],"wp:term":[{"taxonomy":"automobile","embeddable":true,"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/automobile?post=2520"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/www.rossocorsa.gi\/es\/wp-json\/wp\/v2\/features?post=2520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}